{"id":1109,"date":"2021-06-10T16:54:59","date_gmt":"2021-06-10T14:54:59","guid":{"rendered":"https:\/\/fetedelascience.ucly.fr\/?page_id=1109"},"modified":"2026-06-26T14:55:06","modified_gmt":"2026-06-26T12:55:06","slug":"programme-primaire","status":"publish","type":"page","link":"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/","title":{"rendered":"Programme scolaire - Niveau primaire"},"content":{"rendered":"<p>Le Village des Sciences Confluence 2026 r\u00e9unit plusieurs partenaires : <a href=\"https:\/\/www.ucly.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">UCLy<\/a>,\u00a0<a href=\"https:\/\/inl.cnrs.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">INL<\/a>, <a href=\"https:\/\/www.musee-docteur-merieux.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mus\u00e9e des Sciences biologiques du Docteur M\u00e9rieux<\/a>, <a href=\"https:\/\/oberon-sciences.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Oberon Sciences<\/a>.<\/p><h3 class=\"wp-block-heading\"><\/h3><div class=\"wp-block-list js-fade-scroll\">\n  <p class=\"wp-block-list-title\">Ateliers Niveau Primaire 2026<\/p>\n  <div class=\"wp-block-list-intro\"><\/div>\n\n          <a class=\"wp-block-list-item\" href=\"https:\/\/fetedelascience.ucly.fr\/inscription-groupe-scolaire\/\" title=\"Inscription d'un Groupe Scolaire\" target=\"_blank\" >\n      \n        <div class=\"wp-block-list-item-title\">DES MICROBES ET DES HOMMES <\/div>\n        <div class=\"wp-block-list-item-intro\"><p><strong>Du pain qui l\u00e8ve aux yaourts qui fermentent, les microorganismes sont pr\u00e9sents dans notre quotidien.<\/strong><\/p>\n<p>Plongez dans le monde des \u00eatres microscopiques (bact\u00e9ries, levures, virus, moisissures\u2026) et d\u00e9couvrez comment ils transforment ce qui nous entoure. O\u00f9 se cachent-ils dans votre yaourt ? Comment modifient-ils nos aliments\u00a0? Quels sont les bons gestes d\u2019hygi\u00e8ne \u00e0 respecter\u00a0?<\/p>\n<p><strong>Mots-clefs\u00a0:<\/strong> microorganismes, bact\u00e9ries, levures, champignons, virus, fermentation, go\u00fbts, alimentation, microscopes<\/p>\n<p><strong>Dur\u00e9e : 1h30 \u2013 1 classe par cr\u00e9neau<\/strong><\/p>\n<p><strong>Lundi 5 octobre :<\/strong> de 9h30 \u00e0 11h | de 10h15 \u00e0 11h45 | de 13h30 \u00e0 15h | de 14h15 \u00e0 15h45<\/p>\n<p><strong>Mardi 6 octobre : <\/strong>de 9h30 \u00e0 11h | de 10h15 \u00e0 11h45 | de 13h30 \u00e0 15h | de 14h15 \u00e0 15h45<\/p>\n<p><strong>Mercredi 7 octobre :<\/strong> de 9h30 \u00e0 11h | de 10h15 \u00e0 11h45<\/p>\n<p><em>Cet atelier est \u00e9galement accessible aux classes de Maternelle (de 3 \u00e0 6 ans)<\/em><\/p>\n<\/div>\n\n                <span class=\"wp-block-list-item-link\">\n            <span class=\"icon-more\"><\/span>\n          <\/span>\n        <\/a>\n                  <a class=\"wp-block-list-item\" href=\"https:\/\/fetedelascience.ucly.fr\/inscription-groupe-scolaire\/\" title=\"Inscription d'un Groupe Scolaire\" target=\"_blank\" >\n      \n        <div class=\"wp-block-list-item-title\">DE L\u2019ORGANISME \u00c0 L\u2019ADN, ECHELLE DU VIVANT<\/div>\n        <div class=\"wp-block-list-item-intro\"><p><strong>Du visible \u00e0 l\u2019invisible, partez \u00e0 la d\u00e9couverte de l\u2019\u00e9chelle du vivant \u00e0 travers des activit\u00e9s ludiques !<\/strong><\/p>\n<p>Comparez la taille des organismes, observez les microorganismes pr\u00e9sents dans notre quotidien (eau croupie, moisissures de fruits) et d\u00e9couvrez leur r\u00f4le dans la transformation des aliments (fermentation, maturation).<\/p>\n<p>Poursuivez l\u2019exploration avec un focus sur l\u2019ADN avec l\u2019extraction de l\u2019ADN d\u2019un fruit, la banane, et observations des cellules pour comprendre ce qui se cache derri\u00e8re les caract\u00e9ristiques des \u00eatres vivants.<\/p>\n<p><strong>Mots-clefs\u00a0:<\/strong> microorganisme, ADN, cellule, microscopes<\/p>\n<p><strong>Dur\u00e9e : 1h \u2013 1 classe par cr\u00e9neau<\/strong><\/p>\n<p><strong>Lundi 5 octobre : <\/strong>de 10h \u00e0 11h | de 11h \u00e0 12h | de 14h \u00e0 15h | de 15h \u00e0 16h<strong><br \/>\n<\/strong><\/p>\n<p><strong>Mardi 6 octobre : <\/strong>de 10h \u00e0 11h | de 11h \u00e0 12h | de 14h \u00e0 15h | de 15h \u00e0 16h<\/p>\n<p><strong>Mercredi 7 octobre : <\/strong>de 10h \u00e0 11h | de 11h \u00e0 12h<\/p>\n<p><em>Cet atelier est \u00e9galement accessible aux classes de Coll\u00e8ge (de 11 \u00e0 15 ans)<\/em><\/p>\n<\/div>\n\n                <span class=\"wp-block-list-item-link\">\n            <span class=\"icon-more\"><\/span>\n          <\/span>\n        <\/a>\n                  <a class=\"wp-block-list-item\" href=\"https:\/\/fetedelascience.ucly.fr\/inscription-groupe-scolaire\/\" title=\"Inscription d'un Groupe Scolaire\" target=\"_blank\" >\n      \n        <div class=\"wp-block-list-item-title\">DU TRI DES DECHETS \u00c0 LA VALORISATION DU COMPOST<\/div>\n        <div class=\"wp-block-list-item-intro\"><p><strong>Savez-vous qu\u2019une famille de 3 personnes produit plus d\u20191 Tonne de d\u00e9chets\/an?<\/strong><\/p>\n<p>Gr\u00e2ce au tri s\u00e9lectif, une famille de 3 personnes peut recycler environ 520 kg de d\u00e9chets par an, et si elle pratique le compost de ses d\u00e9chets alimentaires elle peut valoriser 250kg\/an de plus. Au total, jusqu\u2019aux \u00be des d\u00e9chets peuvent \u00eatre valoris\u00e9s.<\/p>\n<p>Dans cet atelier, d\u00e9couvrez comment nos restes alimentaires se transforment et participent au cycle du vivant. Au programme : Lecture\/Atelier\/Jeu p\u00e9dagogique sur le tri des d\u00e9chets &#8211; Zoom sur le compost : Pourquoi \u2013 Quoi et Comment composter ? Utilisation du compost et des r\u00e9ponses sous la forme de jeux, de films, d\u2019observations microscopiques\u2026.<\/p>\n<p><strong>Mots-clefs\u00a0:<\/strong> recyclage, d\u00e9chets, compost, d\u00e9composition, microorganismes, vers, insectes, microscopes<\/p>\n<p><strong>Dur\u00e9e : 1h15 \u2013 1 classe par cr\u00e9neau<\/strong><\/p>\n<p><strong>Lundi 5 octobre : <\/strong>de 9h30 \u00e0 10h45 | de 10h45 \u00e0 12h | de 13h30 \u00e0 14h45 | de\u00a0 14h45 \u00e0 16h<strong><br \/>\n<\/strong><\/p>\n<p><strong>Mardi 6 octobre : <\/strong>de 9h30 \u00e0 10h45 | de 10h45 \u00e0 12h | de 13h30 \u00e0 14h45 | de\u00a0 14h45 \u00e0 16h<\/p>\n<p><strong>Mercredi 7 octobre : <\/strong>de 9h30 \u00e0 10h45 | de 10h45 \u00e0 12h<\/p>\n<p><em>Cet atelier est \u00e9galement accessible aux classes de Coll\u00e8ge (de 11 \u00e0 15 ans)<\/em><\/p>\n<\/div>\n\n                <span class=\"wp-block-list-item-link\">\n            <span class=\"icon-more\"><\/span>\n          <\/span>\n        <\/a>\n                  <a class=\"wp-block-list-item\" href=\"https:\/\/fetedelascience.ucly.fr\/inscription-groupe-scolaire\/\" title=\"Inscription d'un Groupe Scolaire\" target=\"_blank\" >\n      \n        <div class=\"wp-block-list-item-title\">PIMENTS, LA SCIENCE QUI PIQUE<\/div>\n        <div class=\"wp-block-list-item-intro\"><p><strong>Vous \u00eates-vous d\u00e9j\u00e0 demand\u00e9s pourquoi les piments piquent ? Pourquoi certains piments sont plus ou moins forts ? <\/strong><\/p>\n<p>Comment classer scientifiquement les piments les uns-par rapport aux autres selon leur intensit\u00e9 ? Au programme 4 activit\u00e9s comprenant des observations \u00e0 la loupe binoculaire et au microscope, la classification de diff\u00e9rents piments sur l\u2019\u00e9chelle de Scoville, une extraction d\u2019ADN de piment et la d\u00e9couverte des applications associ\u00e9es \u00e0 l\u2019utilisation de la mol\u00e9cule responsable du piquant, la capsa\u00efcine.<\/p>\n<p><strong>Dur\u00e9e : 2h \u2013 1 classe par cr\u00e9neau<\/strong><\/p>\n<p><strong>Lundi 5 octobre : <\/strong>de 9h \u00e0 11h | de 13h30 \u00e0 15h30<\/p>\n<p><strong>Mardi 6 octobre : <\/strong>de 9h \u00e0 11h | de 13h30 \u00e0 15h30<\/p>\n<p><strong>Mercredi 7 octobre : <\/strong>de 9h \u00e0 11h<\/p>\n<\/div>\n\n                <span class=\"wp-block-list-item-link\">\n            <span class=\"icon-more\"><\/span>\n          <\/span>\n        <\/a>\n                  <a class=\"wp-block-list-item\" href=\"https:\/\/fetedelascience.ucly.fr\/inscription-groupe-scolaire\/\" title=\"Inscription d'un groupe scolaire\" target=\"\" >\n      \n        <div class=\"wp-block-list-item-title\">DE LA LANGUE AU CERVEAU<\/div>\n        <div class=\"wp-block-list-item-intro\"><p><strong>Pourquoi certains aliments paraissent-ils sucr\u00e9s, amers ou acides ? Comment l\u2019information circule-t-elle de la langue jusqu\u2019au cerveau ?<\/strong><\/p>\n<p>Avec cet atelier, vous menez l\u2019enqu\u00eate sur le parcours de l\u2019information gustative de l\u2019arriv\u00e9e des aliments dans la bouche jusqu\u2019\u00e0 la perception du go\u00fbt par le cerveau. Vous allez explorer le r\u00f4le des r\u00e9cepteurs gustatifs au travers un jeu de carte, reconstruire la transmission nerveuse de l\u2019information, d\u00e9couvrir le r\u00f4le du cerveau dans le traitement du go\u00fbt et enfin observer la structure de la langue \u00e0 l\u2019\u0153il nu et des papilles gustatives au microscope.<\/p>\n<p><strong>Lundi 5 octobre : <\/strong>de 10h \u00e0 12h | de 14h \u00e0 16h<\/p>\n<p><strong>Mardi 6 octobre :<\/strong>de 10h \u00e0 12h | de 14h \u00e0 16h<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\n                <span class=\"wp-block-list-item-link\">\n            <span class=\"icon-more\"><\/span>\n          <\/span>\n        <\/a>\n                  <a class=\"wp-block-list-item\" href=\"https:\/\/fetedelascience.ucly.fr\/inscription-groupe-scolaire\/\" title=\"Inscription d'un groupe scolaire\" target=\"_blank\" >\n      \n        <div class=\"wp-block-list-item-title\">POLLENS : DE LA PLANTE \u00c0 L'ALLERGIE<\/div>\n        <div class=\"wp-block-list-item-intro\"><p><strong>Qu\u2019est ce qu\u2019un pollen ? A quoi sert-il ? Pourquoi d\u00e9clenche-t-il des allergies ? R\u00e9ponses par cet atelier.<\/strong><\/p>\n<p>Ob\u00e9ron Sciences collecte, quantifie et qualifie en temps r\u00e9el les particules contenues dans l&#8217;air et notamment les pollens gr\u00e2ce \u00e0 des capteurs pr\u00e9sents sur tout le territoire fran\u00e7ais. Les pollens ne sont pas tous allergisants. Pour provoquer des sympt\u00f4mes d&#8217;allergie, il est indispensable que les grains de pollens arrivent sur les muqueuses respiratoires de l&#8217;homme. Cet atelier r\u00e9pondra \u00e0 : Qu\u2019est ce qu&#8217;un pollen? d\u2019o\u00f9 vient-il? Pourquoi peut-il rendre les gens malades? comment avons-nous cette information?<\/p>\n<p><strong>Dur\u00e9e : 1h \u2013 1 classe par cr\u00e9neau<\/strong><\/p>\n<p><strong>Lundi 5 octobre : <\/strong>de 10h \u00e0 11h | de 11h \u00e0 12h | de 14h \u00e0 15h | de 15h \u00e0 16h<\/p>\n<p><strong>Mardi 6 octobre : <\/strong>de 10h \u00e0 11h | de 11h \u00e0 12h | de 14h \u00e0 15h | de 15h \u00e0 16h<\/p>\n<\/div>\n\n                <span class=\"wp-block-list-item-link\">\n            <span class=\"icon-more\"><\/span>\n          <\/span>\n        <\/a>\n          <\/div>","protected":false},"excerpt":{"rendered":"<p>Le Village des Sciences Confluence 2026 r\u00e9unit plusieurs partenaires : UCLy,\u00a0INL, Mus\u00e9e des Sciences biologiques du Docteur M\u00e9rieux, Oberon Sciences.<\/p>\n","protected":false},"author":27,"featured_media":2388,"parent":470,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1109","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Programme scolaire - Niveau primaire - F\u00eate de la Science<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programme scolaire - Niveau primaire - F\u00eate de la Science\" \/>\n<meta property=\"og:description\" content=\"Le Village des Sciences Confluence 2026 r\u00e9unit plusieurs partenaires : UCLy,\u00a0INL, Mus\u00e9e des Sciences biologiques du Docteur M\u00e9rieux, Oberon Sciences.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/\" \/>\n<meta property=\"og:site_name\" content=\"F\u00eate de la Science\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-26T12:55:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2025\/07\/fds2024_69_vds-ucly_visee-a-1-804x576.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"804\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/\",\"url\":\"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/\",\"name\":\"Programme scolaire - Niveau primaire - F\u00eate de la Science\",\"isPartOf\":{\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2025\/07\/fds2024_69_vds-ucly_visee-a-1-804x576.jpg\",\"datePublished\":\"2021-06-10T14:54:59+00:00\",\"dateModified\":\"2026-06-26T12:55:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/#primaryimage\",\"url\":\"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2025\/07\/fds2024_69_vds-ucly_visee-a-1-804x576.jpg\",\"contentUrl\":\"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2025\/07\/fds2024_69_vds-ucly_visee-a-1-804x576.jpg\",\"width\":804,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/fetedelascience.ucly.fr\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programme\",\"item\":\"https:\/\/fetedelascience.ucly.fr\/en\/programme\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Programme scolaire - Niveau primaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/#website\",\"url\":\"https:\/\/fetedelascience.ucly.fr\/en\/\",\"name\":\"F\u00eate de la Science\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fetedelascience.ucly.fr\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/#organization\",\"name\":\"F\u00eate de la Science\",\"url\":\"https:\/\/fetedelascience.ucly.fr\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2026\/05\/cropped-logo-fete-de-la-science-estbb-iftlm-blanc-copie.png\",\"contentUrl\":\"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2026\/05\/cropped-logo-fete-de-la-science-estbb-iftlm-blanc-copie.png\",\"width\":400,\"height\":231,\"caption\":\"F\u00eate de la Science\"},\"image\":{\"@id\":\"https:\/\/fetedelascience.ucly.fr\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programme scolaire - Niveau primaire - F\u00eate de la Science","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/","og_locale":"en_US","og_type":"article","og_title":"Programme scolaire - Niveau primaire - F\u00eate de la Science","og_description":"Le Village des Sciences Confluence 2026 r\u00e9unit plusieurs partenaires : UCLy,\u00a0INL, Mus\u00e9e des Sciences biologiques du Docteur M\u00e9rieux, Oberon Sciences.","og_url":"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/","og_site_name":"F\u00eate de la Science","article_modified_time":"2026-06-26T12:55:06+00:00","og_image":[{"width":804,"height":1200,"url":"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2025\/07\/fds2024_69_vds-ucly_visee-a-1-804x576.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/","url":"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/","name":"Programme scolaire - Niveau primaire - F\u00eate de la Science","isPartOf":{"@id":"https:\/\/fetedelascience.ucly.fr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/#primaryimage"},"image":{"@id":"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/#primaryimage"},"thumbnailUrl":"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2025\/07\/fds2024_69_vds-ucly_visee-a-1-804x576.jpg","datePublished":"2021-06-10T14:54:59+00:00","dateModified":"2026-06-26T12:55:06+00:00","breadcrumb":{"@id":"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/#primaryimage","url":"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2025\/07\/fds2024_69_vds-ucly_visee-a-1-804x576.jpg","contentUrl":"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2025\/07\/fds2024_69_vds-ucly_visee-a-1-804x576.jpg","width":804,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/fetedelascience.ucly.fr\/en\/programme\/programme-primaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fetedelascience.ucly.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Programme","item":"https:\/\/fetedelascience.ucly.fr\/en\/programme\/"},{"@type":"ListItem","position":3,"name":"Programme scolaire - Niveau primaire"}]},{"@type":"WebSite","@id":"https:\/\/fetedelascience.ucly.fr\/en\/#website","url":"https:\/\/fetedelascience.ucly.fr\/en\/","name":"F\u00eate de la Science","description":"","publisher":{"@id":"https:\/\/fetedelascience.ucly.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fetedelascience.ucly.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fetedelascience.ucly.fr\/en\/#organization","name":"F\u00eate de la Science","url":"https:\/\/fetedelascience.ucly.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fetedelascience.ucly.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2026\/05\/cropped-logo-fete-de-la-science-estbb-iftlm-blanc-copie.png","contentUrl":"https:\/\/fetedelascience.ucly.fr\/wp-content\/uploads\/sites\/31\/2026\/05\/cropped-logo-fete-de-la-science-estbb-iftlm-blanc-copie.png","width":400,"height":231,"caption":"F\u00eate de la Science"},"image":{"@id":"https:\/\/fetedelascience.ucly.fr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fetedelascience.ucly.fr\/en\/wp-json\/wp\/v2\/pages\/1109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fetedelascience.ucly.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fetedelascience.ucly.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fetedelascience.ucly.fr\/en\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/fetedelascience.ucly.fr\/en\/wp-json\/wp\/v2\/comments?post=1109"}],"version-history":[{"count":2,"href":"https:\/\/fetedelascience.ucly.fr\/en\/wp-json\/wp\/v2\/pages\/1109\/revisions"}],"predecessor-version":[{"id":2720,"href":"https:\/\/fetedelascience.ucly.fr\/en\/wp-json\/wp\/v2\/pages\/1109\/revisions\/2720"}],"up":[{"embeddable":true,"href":"https:\/\/fetedelascience.ucly.fr\/en\/wp-json\/wp\/v2\/pages\/470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fetedelascience.ucly.fr\/en\/wp-json\/wp\/v2\/media\/2388"}],"wp:attachment":[{"href":"https:\/\/fetedelascience.ucly.fr\/en\/wp-json\/wp\/v2\/media?parent=1109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}